{"id":494,"date":"2022-07-21T12:49:15","date_gmt":"2022-07-21T12:49:15","guid":{"rendered":"https:\/\/dils.fr\/favourites\/"},"modified":"2026-07-08T14:49:55","modified_gmt":"2026-07-08T12:49:55","slug":"favourites","status":"publish","type":"page","link":"https:\/\/dils.fr\/en\/favourites\/","title":{"rendered":"Favourites"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"\/www\/dilsmultisite_759\/public\/wp-content\/plugins\/dils-next-portal-properties\/templates\/custom\/template-favourite-properties.blade.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-494","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Your favourite properties - Dils - France<\/title>\n<meta name=\"description\" content=\"Our favourite properties - Dils - France\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dils.fr\/en\/favourites\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Your favourite properties - Dils - France\" \/>\n<meta property=\"og:description\" content=\"Our favourite properties - Dils - France\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dils.fr\/en\/favourites\/\" \/>\n<meta property=\"og:site_name\" content=\"Dils - France\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/social.dils.com\/facebook\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-08T12:49:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dils.fr\/wp-content\/uploads\/sites\/7\/2022\/10\/dils_social.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dils.fr\/en\/favourites\/\",\"url\":\"https:\/\/dils.fr\/en\/favourites\/\",\"name\":\"Your favourite properties - Dils - France\",\"isPartOf\":{\"@id\":\"https:\/\/dils.fr\/en\/#website\"},\"datePublished\":\"2022-07-21T12:49:15+00:00\",\"dateModified\":\"2026-07-08T12:49:55+00:00\",\"description\":\"Our favourite properties - Dils - France\",\"breadcrumb\":{\"@id\":\"https:\/\/dils.fr\/en\/favourites\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dils.fr\/en\/favourites\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dils.fr\/en\/favourites\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/dils.fr\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Favourites\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dils.fr\/en\/#website\",\"url\":\"https:\/\/dils.fr\/en\/\",\"name\":\"Dils - France\",\"description\":\"Rewrite the rules\",\"publisher\":{\"@id\":\"https:\/\/dils.fr\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dils.fr\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dils.fr\/en\/#organization\",\"name\":\"Dils\",\"url\":\"https:\/\/dils.fr\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/dils.fr\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dils.fr\/wp-content\/uploads\/sites\/7\/2022\/10\/dils_social.png\",\"contentUrl\":\"https:\/\/dils.fr\/wp-content\/uploads\/sites\/7\/2022\/10\/dils_social.png\",\"width\":1080,\"height\":1080,\"caption\":\"Dils\"},\"image\":{\"@id\":\"https:\/\/dils.fr\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/social.dils.com\/facebook\/\",\"https:\/\/social.dils.com\/instagram\/\",\"https:\/\/social.dils.com\/linkedin\/\",\"https:\/\/social.dils.com\/youtube\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Your favourite properties - Dils - France","description":"Our favourite properties - Dils - France","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dils.fr\/en\/favourites\/","og_locale":"en_US","og_type":"article","og_title":"Your favourite properties - Dils - France","og_description":"Our favourite properties - Dils - France","og_url":"https:\/\/dils.fr\/en\/favourites\/","og_site_name":"Dils - France","article_publisher":"https:\/\/social.dils.com\/facebook\/","article_modified_time":"2026-07-08T12:49:55+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/dils.fr\/wp-content\/uploads\/sites\/7\/2022\/10\/dils_social.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dils.fr\/en\/favourites\/","url":"https:\/\/dils.fr\/en\/favourites\/","name":"Your favourite properties - Dils - France","isPartOf":{"@id":"https:\/\/dils.fr\/en\/#website"},"datePublished":"2022-07-21T12:49:15+00:00","dateModified":"2026-07-08T12:49:55+00:00","description":"Our favourite properties - Dils - France","breadcrumb":{"@id":"https:\/\/dils.fr\/en\/favourites\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dils.fr\/en\/favourites\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dils.fr\/en\/favourites\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dils.fr\/en\/"},{"@type":"ListItem","position":2,"name":"Favourites"}]},{"@type":"WebSite","@id":"https:\/\/dils.fr\/en\/#website","url":"https:\/\/dils.fr\/en\/","name":"Dils - France","description":"Rewrite the rules","publisher":{"@id":"https:\/\/dils.fr\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dils.fr\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/dils.fr\/en\/#organization","name":"Dils","url":"https:\/\/dils.fr\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dils.fr\/en\/#\/schema\/logo\/image\/","url":"https:\/\/dils.fr\/wp-content\/uploads\/sites\/7\/2022\/10\/dils_social.png","contentUrl":"https:\/\/dils.fr\/wp-content\/uploads\/sites\/7\/2022\/10\/dils_social.png","width":1080,"height":1080,"caption":"Dils"},"image":{"@id":"https:\/\/dils.fr\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/social.dils.com\/facebook\/","https:\/\/social.dils.com\/instagram\/","https:\/\/social.dils.com\/linkedin\/","https:\/\/social.dils.com\/youtube\/"]}]}},"_links":{"self":[{"href":"https:\/\/dils.fr\/en\/wp-json\/wp\/v2\/pages\/494","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dils.fr\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dils.fr\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dils.fr\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/dils.fr\/en\/wp-json\/wp\/v2\/comments?post=494"}],"version-history":[{"count":1,"href":"https:\/\/dils.fr\/en\/wp-json\/wp\/v2\/pages\/494\/revisions"}],"predecessor-version":[{"id":48965,"href":"https:\/\/dils.fr\/en\/wp-json\/wp\/v2\/pages\/494\/revisions\/48965"}],"wp:attachment":[{"href":"https:\/\/dils.fr\/en\/wp-json\/wp\/v2\/media?parent=494"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}